{"id":6516,"date":"2022-04-21T13:37:23","date_gmt":"2022-04-21T13:37:23","guid":{"rendered":"https:\/\/energystudio-agency.ro\/demo13\/?post_type=product&#038;p=6516"},"modified":"2022-08-03T05:49:42","modified_gmt":"2022-08-03T05:49:42","slug":"rochie-la-donna","status":"publish","type":"product","link":"https:\/\/energystudio-agency.ro\/demo13\/produs\/rochie-la-donna\/","title":{"rendered":"Rochie Ladonna"},"content":{"rendered":"<p>Ai curaj sa iesi din anonimat cu Rochia Ladona verde.<\/p>\n<p>Se spune ca verdele este o culoare care insufla claritate mentala \u015fi optimism. Pai de ce altceva ai avea nevoie mai mult pentru a avea incredere in tine.<br \/>\nRochia Ladona este vaporoasa si te va ajuta sa te simti feminina si confortabila la fiecare pas.<br \/>\nImprimeul cu paiete de la baza gatului completeaza perfect tinuta iar sigurele accesorii ce mai e necesar sa le adaugi sunt o pereche de cercei cu pietre si pantofi cu toc.<\/p>\n<p>Sa inceapa petrecerea!<\/p>\n","protected":false},"excerpt":{"rendered":"<p><strong>Material \u0219i \u00eengrijire<\/strong><\/p>\n<ul>\n<li>Material: 100% Poliester<\/li>\n<li>\u021aara de origine: Italia<\/li>\n<\/ul>\n","protected":false},"featured_media":6440,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[38],"product_tag":[],"class_list":["post-6516","product","type-product","status-publish","has-post-thumbnail","product_cat-elegant","first","instock","sale","shipping-taxable","purchasable","product-type-variable"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rochie Ladonna - energystudio demo shop<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/energystudio-agency.ro\/demo13\/produs\/rochie-la-donna\/\" \/>\n<meta property=\"og:locale\" content=\"ro_RO\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rochie Ladonna - energystudio demo shop\" \/>\n<meta property=\"og:description\" content=\"Material \u0219i \u00eengrijire   Material: 100% Poliester  \u021aara de origine: Italia\" \/>\n<meta property=\"og:url\" content=\"https:\/\/energystudio-agency.ro\/demo13\/produs\/rochie-la-donna\/\" \/>\n<meta property=\"og:site_name\" content=\"energystudio demo shop\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Carddinale-106408828691151\" \/>\n<meta property=\"article:modified_time\" content=\"2022-08-03T05:49:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/energystudio-agency.ro\/demo13\/wp-content\/uploads\/2022\/04\/DSC01390-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1707\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/energystudio-agency.ro\\\/demo13\\\/produs\\\/rochie-la-donna\\\/\",\"url\":\"https:\\\/\\\/energystudio-agency.ro\\\/demo13\\\/produs\\\/rochie-la-donna\\\/\",\"name\":\"Rochie Ladonna - energystudio demo shop\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/energystudio-agency.ro\\\/demo13\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/energystudio-agency.ro\\\/demo13\\\/produs\\\/rochie-la-donna\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/energystudio-agency.ro\\\/demo13\\\/produs\\\/rochie-la-donna\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/energystudio-agency.ro\\\/demo13\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/DSC01390-scaled.jpg\",\"datePublished\":\"2022-04-21T13:37:23+00:00\",\"dateModified\":\"2022-08-03T05:49:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/energystudio-agency.ro\\\/demo13\\\/produs\\\/rochie-la-donna\\\/#breadcrumb\"},\"inLanguage\":\"ro-RO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/energystudio-agency.ro\\\/demo13\\\/produs\\\/rochie-la-donna\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ro-RO\",\"@id\":\"https:\\\/\\\/energystudio-agency.ro\\\/demo13\\\/produs\\\/rochie-la-donna\\\/#primaryimage\",\"url\":\"https:\\\/\\\/energystudio-agency.ro\\\/demo13\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/DSC01390-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/energystudio-agency.ro\\\/demo13\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/DSC01390-scaled.jpg\",\"width\":1707,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/energystudio-agency.ro\\\/demo13\\\/produs\\\/rochie-la-donna\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Prima pagin\u0103\",\"item\":\"https:\\\/\\\/energystudio-agency.ro\\\/demo13\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Magazin\",\"item\":\"https:\\\/\\\/energystudio-agency.ro\\\/demo13\\\/magazin\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Rochie Ladonna\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/energystudio-agency.ro\\\/demo13\\\/#website\",\"url\":\"https:\\\/\\\/energystudio-agency.ro\\\/demo13\\\/\",\"name\":\"energystudio demo shop\",\"description\":\"magazin online\",\"publisher\":{\"@id\":\"https:\\\/\\\/energystudio-agency.ro\\\/demo13\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/energystudio-agency.ro\\\/demo13\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ro-RO\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/energystudio-agency.ro\\\/demo13\\\/#organization\",\"name\":\"Carddinale haine dama\",\"url\":\"https:\\\/\\\/energystudio-agency.ro\\\/demo13\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ro-RO\",\"@id\":\"https:\\\/\\\/energystudio-agency.ro\\\/demo13\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/energystudio-agency.ro\\\/demo13\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Logo_Salon_Carddinale-1.png\",\"contentUrl\":\"https:\\\/\\\/energystudio-agency.ro\\\/demo13\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Logo_Salon_Carddinale-1.png\",\"width\":6245,\"height\":1018,\"caption\":\"Carddinale haine dama\"},\"image\":{\"@id\":\"https:\\\/\\\/energystudio-agency.ro\\\/demo13\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Carddinale-106408828691151\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rochie Ladonna - energystudio demo shop","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/energystudio-agency.ro\/demo13\/produs\/rochie-la-donna\/","og_locale":"ro_RO","og_type":"article","og_title":"Rochie Ladonna - energystudio demo shop","og_description":"Material \u0219i \u00eengrijire   Material: 100% Poliester  \u021aara de origine: Italia","og_url":"https:\/\/energystudio-agency.ro\/demo13\/produs\/rochie-la-donna\/","og_site_name":"energystudio demo shop","article_publisher":"https:\/\/www.facebook.com\/Carddinale-106408828691151","article_modified_time":"2022-08-03T05:49:42+00:00","og_image":[{"width":1707,"height":2560,"url":"https:\/\/energystudio-agency.ro\/demo13\/wp-content\/uploads\/2022\/04\/DSC01390-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/energystudio-agency.ro\/demo13\/produs\/rochie-la-donna\/","url":"https:\/\/energystudio-agency.ro\/demo13\/produs\/rochie-la-donna\/","name":"Rochie Ladonna - energystudio demo shop","isPartOf":{"@id":"https:\/\/energystudio-agency.ro\/demo13\/#website"},"primaryImageOfPage":{"@id":"https:\/\/energystudio-agency.ro\/demo13\/produs\/rochie-la-donna\/#primaryimage"},"image":{"@id":"https:\/\/energystudio-agency.ro\/demo13\/produs\/rochie-la-donna\/#primaryimage"},"thumbnailUrl":"https:\/\/energystudio-agency.ro\/demo13\/wp-content\/uploads\/2022\/04\/DSC01390-scaled.jpg","datePublished":"2022-04-21T13:37:23+00:00","dateModified":"2022-08-03T05:49:42+00:00","breadcrumb":{"@id":"https:\/\/energystudio-agency.ro\/demo13\/produs\/rochie-la-donna\/#breadcrumb"},"inLanguage":"ro-RO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/energystudio-agency.ro\/demo13\/produs\/rochie-la-donna\/"]}]},{"@type":"ImageObject","inLanguage":"ro-RO","@id":"https:\/\/energystudio-agency.ro\/demo13\/produs\/rochie-la-donna\/#primaryimage","url":"https:\/\/energystudio-agency.ro\/demo13\/wp-content\/uploads\/2022\/04\/DSC01390-scaled.jpg","contentUrl":"https:\/\/energystudio-agency.ro\/demo13\/wp-content\/uploads\/2022\/04\/DSC01390-scaled.jpg","width":1707,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/energystudio-agency.ro\/demo13\/produs\/rochie-la-donna\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Prima pagin\u0103","item":"https:\/\/energystudio-agency.ro\/demo13\/"},{"@type":"ListItem","position":2,"name":"Magazin","item":"https:\/\/energystudio-agency.ro\/demo13\/magazin\/"},{"@type":"ListItem","position":3,"name":"Rochie Ladonna"}]},{"@type":"WebSite","@id":"https:\/\/energystudio-agency.ro\/demo13\/#website","url":"https:\/\/energystudio-agency.ro\/demo13\/","name":"energystudio demo shop","description":"magazin online","publisher":{"@id":"https:\/\/energystudio-agency.ro\/demo13\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/energystudio-agency.ro\/demo13\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ro-RO"},{"@type":"Organization","@id":"https:\/\/energystudio-agency.ro\/demo13\/#organization","name":"Carddinale haine dama","url":"https:\/\/energystudio-agency.ro\/demo13\/","logo":{"@type":"ImageObject","inLanguage":"ro-RO","@id":"https:\/\/energystudio-agency.ro\/demo13\/#\/schema\/logo\/image\/","url":"https:\/\/energystudio-agency.ro\/demo13\/wp-content\/uploads\/2022\/03\/Logo_Salon_Carddinale-1.png","contentUrl":"https:\/\/energystudio-agency.ro\/demo13\/wp-content\/uploads\/2022\/03\/Logo_Salon_Carddinale-1.png","width":6245,"height":1018,"caption":"Carddinale haine dama"},"image":{"@id":"https:\/\/energystudio-agency.ro\/demo13\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Carddinale-106408828691151"]}]}},"_links":{"self":[{"href":"https:\/\/energystudio-agency.ro\/demo13\/wp-json\/wp\/v2\/product\/6516","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/energystudio-agency.ro\/demo13\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/energystudio-agency.ro\/demo13\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/energystudio-agency.ro\/demo13\/wp-json\/wp\/v2\/comments?post=6516"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/energystudio-agency.ro\/demo13\/wp-json\/wp\/v2\/media\/6440"}],"wp:attachment":[{"href":"https:\/\/energystudio-agency.ro\/demo13\/wp-json\/wp\/v2\/media?parent=6516"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/energystudio-agency.ro\/demo13\/wp-json\/wp\/v2\/product_brand?post=6516"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/energystudio-agency.ro\/demo13\/wp-json\/wp\/v2\/product_cat?post=6516"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/energystudio-agency.ro\/demo13\/wp-json\/wp\/v2\/product_tag?post=6516"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}