{"id":232,"date":"2021-08-26T14:39:51","date_gmt":"2021-08-26T14:39:51","guid":{"rendered":"http:\/\/dummy.xtemos.com\/woodmart2\/elementor\/?post_type=product&#038;p=232"},"modified":"2023-07-11T08:57:52","modified_gmt":"2023-07-11T08:57:52","slug":"eames-lounge-chair","status":"publish","type":"product","link":"https:\/\/energystudio-agency.ro\/demo17\/produs\/eames-lounge-chair\/","title":{"rendered":"Cpu Liquid"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"232\" class=\"elementor elementor-232\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-70334114 wd-section-stretch opacity-video-bg elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"70334114\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;video&quot;,&quot;background_video_link&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=IYwPMtx38Eg&quot;}\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-background-video-container elementor-hidden-mobile\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-background-video-embed\" role=\"presentation\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-25c1d3\" data-id=\"25c1d3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-4fb1a9ea elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4fb1a9ea\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-44b90b22\" data-id=\"44b90b22\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4f31b8d8 wd-width-100 elementor-widget elementor-widget-wd_title\" data-id=\"4f31b8d8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"title-wrapper set-mb-s reset-last-child wd-title-color-white wd-title-style-simple wd-title-size-extra-large text-center\">\n\n\t\t\t\t\t\t\t<div class=\"title-subtitle subtitle-color-white subtitle-style-default wd-fontsize-m\">\n\t\t\t\t\tCHARLES &amp; RAY EAMES, 1956\t\t\t\t<\/div>\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h4 class=\"woodmart-title-container title wd-fontsize-xxxl\">Lounge Chair<\/h4> \n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"title-after_title set-cont-mb-s reset-last-child wd-fontsize-s\">\n\t\t\t\t\tAmet nibh vel tristique dui id ridiculus ligula scelerisque faucibus platea a est imperdiet parturient aliquam taciti parturient.\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-551a20e8 elementor-widget__width-auto elementor-widget elementor-widget-wd_button\" data-id=\"551a20e8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"wd-button-wrapper text-center\" >\n\t\t\t<a class=\"btn btn-style-default btn-style-rectangle btn-size-default btn-color-white btn-icon-pos-right\"  href=\"#\">\n\t\t\t\t<span class=\"wd-btn-text\" data-elementor-setting-key=\"text\">\n\t\t\t\t\tADD TO CART\t\t\t\t<\/span>\n\n\t\t\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-662c33ad elementor-widget__width-auto elementor-widget elementor-widget-wd_button\" data-id=\"662c33ad\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"wd-button-wrapper text-center\" >\n\t\t\t<a class=\"btn btn-style-bordered btn-style-rectangle btn-size-default btn-color-white btn-icon-pos-right\"  href=\"#\">\n\t\t\t\t<span class=\"wd-btn-text\" data-elementor-setting-key=\"text\">\n\t\t\t\t\tVIEW MORE\t\t\t\t<\/span>\n\n\t\t\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3997d6e4 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3997d6e4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-604104\" data-id=\"604104\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-70f8881e elementor-widget elementor-widget-wd_3d_view\" data-id=\"70f8881e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_3d_view.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"wd-threed-view\" data-args='{\"frames_count\":9,\"images\":[false,false,false,false,false,false,false,false,false],\"width\":null,\"height\":null}'>\n\t\t\t<ul class=\"threed-view-images\"><\/ul>\n\t\t\t<div class=\"spinner\">\n\t\t\t\t<span>0%<\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-164f8524 text-center\" data-id=\"164f8524\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-503ac0eb wd-width-100 elementor-widget elementor-widget-wd_title\" data-id=\"503ac0eb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"title-wrapper set-mb-s reset-last-child wd-title-color-default wd-title-style-default wd-title-size-extra-large text-center\">\n\n\t\t\t\t\t\t\t<div class=\"title-subtitle subtitle-color-default subtitle-style-default wd-fontsize-m\">\n\t\t\t\t\tWHAT'S IN IT FOR YOU\t\t\t\t<\/div>\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h4 class=\"woodmart-title-container title wd-fontsize-xxxl\">Eames Lounge<br \/>\r\nChair &amp; Ottoman<\/h4> \n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"title-after_title set-cont-mb-s reset-last-child wd-fontsize-s\">\n\t\t\t\t\tAmet nibh vel tristique dui id ridiculus ligula scelerisque faucibus platea a est imperdiet parturient aliquam taciti parturient odio a mi auctor rhoncus nec sociis natoque dui. Urna lacinia condimentum mi inceptos.\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-231c02e1 elementor-widget__width-auto elementor-widget elementor-widget-wd_button\" data-id=\"231c02e1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"wd-button-wrapper text-center\" >\n\t\t\t<a class=\"btn btn-style-default btn-style-rectangle btn-size-default btn-color-black btn-icon-pos-right\"  href=\"#\">\n\t\t\t\t<span class=\"wd-btn-text\" data-elementor-setting-key=\"text\">\n\t\t\t\t\tSHOP NOW\t\t\t\t<\/span>\n\n\t\t\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-32f84899 elementor-widget__width-auto elementor-widget elementor-widget-wd_button\" data-id=\"32f84899\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"wd-button-wrapper text-center\" >\n\t\t\t<a class=\"btn btn-style-bordered btn-style-rectangle btn-size-default btn-color-default btn-icon-pos-right\"  href=\"#\">\n\t\t\t\t<span class=\"wd-btn-text\" data-elementor-setting-key=\"text\">\n\t\t\t\t\tVIEW MORE\t\t\t\t<\/span>\n\n\t\t\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-673bcda3 elementor-section-content-top elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"673bcda3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7e0b3d07\" data-id=\"7e0b3d07\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2a293777 wd-width-100 elementor-widget elementor-widget-wd_title\" data-id=\"2a293777\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"title-wrapper set-mb-s reset-last-child wd-title-color-default wd-title-style-default wd-title-size-medium text-center\">\n\n\t\t\t\t\t\t\t<div class=\"title-subtitle subtitle-color-default subtitle-style-default wd-fontsize-xs\">\n\t\t\t\t\tWOODEN MATERIALS\t\t\t\t<\/div>\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h4 class=\"woodmart-title-container title wd-fontsize-xl\">SEAT AND BACK SHELL<\/h4> \n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"title-after_title set-cont-mb-s reset-last-child wd-fontsize-s\">\n\t\t\t\t\tAmet nibh vel tristique dui id ridiculus ligula scelerisque faucibus platea a est imperdiet parturient aliquam taciti parturient.\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3074a9f\" data-id=\"3074a9f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4c53117f wd-width-100 elementor-widget elementor-widget-wd_title\" data-id=\"4c53117f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"title-wrapper set-mb-s reset-last-child wd-title-color-default wd-title-style-default wd-title-size-medium text-center\">\n\n\t\t\t\t\t\t\t<div class=\"title-subtitle subtitle-color-default subtitle-style-default wd-fontsize-xs\">\n\t\t\t\t\tTEXTILES MATERIALS\t\t\t\t<\/div>\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h4 class=\"woodmart-title-container title wd-fontsize-xl\">LEATHER PREMIUM<\/h4> \n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"title-after_title set-cont-mb-s reset-last-child wd-fontsize-s\">\n\t\t\t\t\tAmet nibh vel tristique dui id ridiculus ligula scelerisque faucibus platea a est imperdiet parturient aliquam taciti parturient.\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Scelerisque facilisi rhoncus non faucibus parturient senectus lobortis a ullamcorper vestibulum mi nibh ultricies a parturient gravida a vestibulum leo sem in. Est cum torquent mi in scelerisque leo aptent per at vitae ante eleifend mollis adipiscing.<\/p>\n","protected":false},"featured_media":5288,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[32],"product_tag":[],"class_list":["post-232","product","type-product","status-publish","has-post-thumbnail","product_cat-sisteme-pc","first","instock","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/energystudio-agency.ro\/demo17\/wp-json\/wp\/v2\/product\/232","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/energystudio-agency.ro\/demo17\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/energystudio-agency.ro\/demo17\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/energystudio-agency.ro\/demo17\/wp-json\/wp\/v2\/comments?post=232"}],"version-history":[{"count":0,"href":"https:\/\/energystudio-agency.ro\/demo17\/wp-json\/wp\/v2\/product\/232\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/energystudio-agency.ro\/demo17\/wp-json\/wp\/v2\/media\/5288"}],"wp:attachment":[{"href":"https:\/\/energystudio-agency.ro\/demo17\/wp-json\/wp\/v2\/media?parent=232"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/energystudio-agency.ro\/demo17\/wp-json\/wp\/v2\/product_brand?post=232"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/energystudio-agency.ro\/demo17\/wp-json\/wp\/v2\/product_cat?post=232"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/energystudio-agency.ro\/demo17\/wp-json\/wp\/v2\/product_tag?post=232"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}